{"id":15091,"date":"2017-06-14T09:23:16","date_gmt":"2017-06-14T09:23:16","guid":{"rendered":"https:\/\/mashreq.com.my\/home-base\/"},"modified":"2022-01-27T08:14:20","modified_gmt":"2022-01-27T08:14:20","slug":"home-base","status":"publish","type":"page","link":"https:\/\/mashreq.com.my\/ar\/","title":{"rendered":"Home base"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; css=&#8221;.vc_custom_1496220814548{margin-top: -40px !important;margin-bottom: 8vh !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1496220809434{padding-top: 0px !important;}&#8221;][rev_slider_vc alias=&#8221;main-slider-1&#8243;][\/vc_column][\/vc_row][vc_row woodmart_disable_overflow=&#8221;1&#8243; css=&#8221;.vc_custom_1496402498927{margin-bottom: 8vh !important;}&#8221; el_class=&#8221;bg-bottom&#8221;][vc_column 0=&#8221;&#8221; css=&#8221;.vc_custom_1496220821354{padding-top: 0px !important;}&#8221;]\n\t\t<div id=\"wd-61f25034608e9\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-61f25034608e9 wd-title-color-default wd-title-style-default text-center  wd-underline-colored\">\n\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"title-subtitle  subtitle-color-default font-default subtitle-style-default wd-font-weight- wd-fontsize-xs\">\u0645\u062c\u0645\u0648\u0639\u0629 \u0627\u0644\u0645\u0634\u0631\u0642 \u0627\u0644\u0645\u0645\u064a\u0632\u0629<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xl\" >\u0643\u062a\u0628 \u0645\u0645\u064a\u0632\u0629<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"title-after_title reset-last-child  wd-fontsize-s\">\u0627\u0648\u0644 \u0645\u0643\u062a\u0628\u0647 \u0644\u0644\u0643\u062a\u0628 \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0641\u064a \u0645\u0627\u0644\u064a\u0632\u064a\u0627<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t\t<div id=\"\" class=\"wd-products-element wd-wpb\">\n\t\t\t\n\t\t\n\t\t\t\t\t<div class=\"products wd-products  grid-columns-4 elements-grid wd-grid-g\" data-paged=\"1\" data-atts=\"{&quot;columns&quot;:&quot;4&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;highlighted_products&quot;:&quot;0&quot;,&quot;products_bordered_grid&quot;:&quot;0&quot;,&quot;force_not_ajax&quot;:&quot;no&quot;}\" data-source=\"shortcode\" data-columns=\"4\" data-grid-gallery=\"\" style=\"--wd-col-lg:4;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:30px;--wd-gap-sm:10px;\">\n\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-27601 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"27601\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-scaled-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-id=\"27601\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\">(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>85&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0633\u0645 \u0627\u0644\u0643\u062a\u0627\u0628: \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u0651\u064e\u062d\u0652\u0648\u061f\r\n\u0627\u0644\u0645\u0624\u0644\u0641: \u0623\u062d\u0645\u062f \u0625\u0633\u0643\u0646\u062f\u0631.\r\n\u0627\u0644\u0646\u0627\u0634\u0631: \u062f\u0627\u0631 \u0627\u0644\u0644\u0624\u0644\u0624\u0629 \u0644\u0644\u0646\u0634\u0631 \u0648\u0627\u0644\u062a\u0648\u0632\u064a\u0639 (\u0627\u0644\u0645\u0646\u0635\u0648\u0631\u0629 - \u0645\u0635\u0631).\r\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629: \u0627\u0644\u0637\u0628\u0639\u0629 \u0627\u0644\u062a\u0627\u0633\u0639\u0629 \u0639\u0634\u0631\u0629 (2024 \u0645 - 1445 \u0647\u0640).\r\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641: \u063a\u0644\u0627\u0641 \u0648\u0631\u0642\u064a \u0639\u0627\u062f\u064a (Paperback).\r\n\u0631\u0642\u0645 \u0627\u0644\u0625\u064a\u062f\u0627\u0639: 4153 \/ 2022 \u0645.\r\n\r\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a: 552\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-key=\"ad63541d4f\" data-product-id=\"27601\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27601\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27601\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27601\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27601\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27601\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-25672 status-publish instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"2\" data-id=\"25672\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-id=\"25672\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\">11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>15&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u0639\u0635\u0627\u0645 \u0645\u0646\u0635\u0648\u0631\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:172\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0634\u0631\u0648\u0642\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-key=\"ad63541d4f\" data-product-id=\"25672\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25672\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25672\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25672\" data-product_sku=\"MASHCODE142\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25672\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25672\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-25575 status-publish last instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"3\" data-id=\"25575\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"1984\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"1984\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-id=\"25575\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\">1984<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u062c\u0648\u0631\u062c \u0627\u0648\u0631\u064a\u0644\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:400\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0628\u064a\u0627\u0646\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-key=\"ad63541d4f\" data-product-id=\"25575\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25575\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25575\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25575\" data-product_sku=\"9789775239938\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;1984&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;1984&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25575\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25575\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-24607 status-publish first instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"4\" data-id=\"24607\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-id=\"24607\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\">200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>11&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u062d\u0627\u0641\u0638 \u0628\u0646 \u0623\u062d\u0645\u062f \u062d\u0643\u0645\u0649\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:159\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0641\u0636\u064a\u0644\u0629\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-key=\"ad63541d4f\" data-product-id=\"24607\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24607\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24607\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24607\" data-product_sku=\"9772972298\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24607\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24607\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-27450 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"27450\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-id=\"27450\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\">Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthors: Sulaiman Ismail &amp; Yuslina Mohamed\r\nNumber of Pages: 153\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-key=\"ad63541d4f\" data-product-id=\"27450\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27450\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27450\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27450\" data-product_sku=\"MashreqPub1\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27450\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27450\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-24896 status-publish instock product_cat-811 has-post-thumbnail purchasable product-type-simple\" data-loop=\"6\" data-id=\"24896\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" data-id=\"13596\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\">Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>60&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641: \u0645\u062e\u062a\u0627\u0631 \u0627\u0644\u0637\u0627\u0647\u0631 \u062d\u0633\u064a\u0646\r\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a: 195\r\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0643\u062a\u0627\u0628 \u0645\u0639 CD\r\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\r\n\u0627\u0644\u0646\u0627\u0634\u0631: \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0644\u0644\u062c\u0645\u064a\u0639\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" data-key=\"ad63541d4f\" data-product-id=\"13596\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24896\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24896\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24896\" data-product_sku=\"Child1160\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24896\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24896\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-27451 status-publish last instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"27451\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Beyond Borders &#8211; Circular Economy And Marketing\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" data-id=\"27451\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\">Beyond Borders &#8211; Circular Economy And Marketing<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Muhammad Tahir\r\nNumber of Pages: 128\r\nCover Type: Hardcover\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" data-key=\"ad63541d4f\" data-product-id=\"27451\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27451\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27451\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27451\" data-product_sku=\"MashreqPub2\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Beyond Borders - Circular Economy And Marketing&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Beyond Borders - Circular Economy And Marketing&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27451\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27451\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-27452 status-publish first instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"27452\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" data-id=\"27452\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\">Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>28&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Ali Ali Gobaili Saged\r\nNumber of Pages: 130\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" data-key=\"ad63541d4f\" data-product-id=\"27452\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27452\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27452\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27452\" data-product_sku=\"MashreqPub3\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27452\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27452\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-27453 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"9\" data-id=\"27453\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Humanizing Science Education &#8211; STS as a Model\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" data-id=\"27453\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\">Humanizing Science Education &#8211; STS as a Model<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Muhammad Yusuf\r\nNumber of Pages: 146\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" data-key=\"ad63541d4f\" data-product-id=\"27453\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27453\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27453\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27453\" data-product_sku=\"MashreqPub4\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Humanizing Science Education - STS as a Model&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Humanizing Science Education - STS as a Model&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27453\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27453\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-27454 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"10\" data-id=\"27454\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Influence of Media on People and Society\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" data-id=\"27454\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\">Influence of Media on People and Society<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Ahmed Abdel-Malik\r\nNumber of Pages: 123\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" data-key=\"ad63541d4f\" data-product-id=\"27454\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27454\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27454\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27454\" data-product_sku=\"MashreqPub5\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Influence of Media on People and Society&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Influence of Media on People and Society&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27454\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27454\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-27455 status-publish last instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"11\" data-id=\"27455\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-1\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Islamic Studies Book 1\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-1\/\" data-id=\"27455\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-1\/\">Islamic Studies Book 1<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>50&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Imam Nurdin Muhammad Ali\r\nNumber of Pages: 137\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-1\/\" data-key=\"ad63541d4f\" data-product-id=\"27455\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27455\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27455\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27455\" data-product_sku=\"MashreqPub6\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Islamic Studies Book 1&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Islamic Studies Book 1&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27455\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-1\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27455\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-27456 status-publish first instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"12\" data-id=\"27456\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-2\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Islamic Studies Book 2\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-2\/\" data-id=\"27456\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-2\/\">Islamic Studies Book 2<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>50&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Imam Nurdin Muhammad Ali\r\nNumber of Pages: 132\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Dar Al-Mashreq International Book House\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-2\/\" data-key=\"ad63541d4f\" data-product-id=\"27456\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27456\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27456\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27456\" data-product_sku=\"MashreqPub7\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Islamic Studies Book 2&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Islamic Studies Book 2&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27456\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-2\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27456\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; disable_element=&#8221;yes&#8221; woodmart_bg_position=&#8221;left-bottom&#8221; woodmart_disable_overflow=&#8221;1&#8243; css=&#8221;.vc_custom_1635919164032{margin-bottom: 0px !important;padding-bottom: 8vh !important;background-image: url(https:\/\/mashreq.com.mywp-content\/uploads\/2017\/06\/wood-o-background.svg?id=215) !important;background-position: 0 0 !important;background-repeat: no-repeat !important;}&#8221; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243;][vc_column 0=&#8221;&#8221; css=&#8221;.vc_custom_1496220834961{padding-top: 0px !important;}&#8221;]\n\t\t<div id=\"wd-5e5deb538499b\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5e5deb538499b wd-title-color-default wd-title-style-default text-center vc_custom_1583213433927 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xl\" >FEATURED BOOKS<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"title-after_title reset-last-child  wd-fontsize-s\">Visit our shop to see amazing Collections from our Authors.<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t<div id=\"wd-6a5787c7d1a3d\" class=\"wd-tabs wd-products-tabs wd-wpb tabs-wd-6a5787c7d1a3d tabs-design-default \">\n\t\t\t<div class=\"wd-tabs-header text-center\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"wd-nav-wrapper wd-nav-tabs-wrapper tabs-navigation-wrapper\">\n\t\t\t\t\t<ul class=\"wd-nav wd-nav-tabs products-tabs-title wd-style-underline wd-icon-pos-left\"><li data-atts=\"{&quot;items_per_page&quot;:&quot;8&quot;,&quot;pagination&quot;:&quot;arrows&quot;,&quot;title&quot;:&quot;BEST SELLERS&quot;,&quot;columns&quot;:&quot;4&quot;,&quot;taxonomies&quot;:&quot;35&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;products_bordered_grid&quot;:&quot;0&quot;,&quot;lazy_loading&quot;:&quot;no&quot;,&quot;icon_size&quot;:&quot;25x25&quot;}\" class=\" wd-active\"><a href=\"#\" class=\"wd-nav-link\"><span class=\"tab-label nav-link-text\">BEST SELLERS<\/span><\/a><\/li><li data-atts=\"{&quot;items_per_page&quot;:&quot;8&quot;,&quot;pagination&quot;:&quot;arrows&quot;,&quot;title&quot;:&quot;FEATURED&quot;,&quot;columns&quot;:&quot;4&quot;,&quot;icon_size&quot;:&quot;25x25&quot;}\" class=\"\"><a href=\"#\" class=\"wd-nav-link\"><span class=\"tab-label nav-link-text\">FEATURED<\/span><\/a><\/li><li data-atts=\"{&quot;items_per_page&quot;:&quot;8&quot;,&quot;pagination&quot;:&quot;arrows&quot;,&quot;title&quot;:&quot;SALES&quot;,&quot;columns&quot;:&quot;4&quot;,&quot;icon_size&quot;:&quot;25x25&quot;}\" class=\"\"><a href=\"#\" class=\"wd-nav-link\"><span class=\"tab-label nav-link-text\">SALES<\/span><\/a><\/li><\/ul>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-tabs-content-wrapper\" >\n\t\t\t\t\t<div class=\"wd-sticky-loader\"><span class=\"wd-loader\"><\/span><\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t<div id=\"\" class=\"wd-products-element wd-wpb wd-tab-content wd-active wd-in\">\n\t\t\t\t\t<div class=\"wd-sticky-loader\"><span class=\"wd-loader\"><\/span><\/div>\n\t\t\n\t\t\n\t\t\t\t\t<div class=\"products wd-products  grid-columns-4 elements-grid pagination-arrows wd-grid-g\" data-paged=\"1\" data-atts=\"{&quot;taxonomies&quot;:&quot;35&quot;,&quot;pagination&quot;:&quot;arrows&quot;,&quot;items_per_page&quot;:&quot;8&quot;,&quot;columns&quot;:&quot;4&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;products_bordered_grid&quot;:&quot;0&quot;,&quot;force_not_ajax&quot;:&quot;no&quot;,&quot;wrapper_classes&quot;:&quot; wd-tab-content wd-active wd-in&quot;}\" data-source=\"shortcode\" data-columns=\"4\" data-grid-gallery=\"\" style=\"--wd-col-lg:4;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:30px;--wd-gap-sm:10px;\">\n\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-27601 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"27601\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-scaled-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-id=\"27601\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\">(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>85&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0633\u0645 \u0627\u0644\u0643\u062a\u0627\u0628: \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u0651\u064e\u062d\u0652\u0648\u061f\r\n\u0627\u0644\u0645\u0624\u0644\u0641: \u0623\u062d\u0645\u062f \u0625\u0633\u0643\u0646\u062f\u0631.\r\n\u0627\u0644\u0646\u0627\u0634\u0631: \u062f\u0627\u0631 \u0627\u0644\u0644\u0624\u0644\u0624\u0629 \u0644\u0644\u0646\u0634\u0631 \u0648\u0627\u0644\u062a\u0648\u0632\u064a\u0639 (\u0627\u0644\u0645\u0646\u0635\u0648\u0631\u0629 - \u0645\u0635\u0631).\r\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629: \u0627\u0644\u0637\u0628\u0639\u0629 \u0627\u0644\u062a\u0627\u0633\u0639\u0629 \u0639\u0634\u0631\u0629 (2024 \u0645 - 1445 \u0647\u0640).\r\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641: \u063a\u0644\u0627\u0641 \u0648\u0631\u0642\u064a \u0639\u0627\u062f\u064a (Paperback).\r\n\u0631\u0642\u0645 \u0627\u0644\u0625\u064a\u062f\u0627\u0639: 4153 \/ 2022 \u0645.\r\n\r\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a: 552\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-key=\"ad63541d4f\" data-product-id=\"27601\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27601\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27601\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27601\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27601\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27601\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-25672 status-publish instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"2\" data-id=\"25672\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-id=\"25672\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\">11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>15&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u0639\u0635\u0627\u0645 \u0645\u0646\u0635\u0648\u0631\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:172\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0634\u0631\u0648\u0642\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-key=\"ad63541d4f\" data-product-id=\"25672\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25672\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25672\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25672\" data-product_sku=\"MASHCODE142\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25672\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25672\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-25575 status-publish last instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"3\" data-id=\"25575\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"1984\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"1984\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-id=\"25575\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\">1984<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u062c\u0648\u0631\u062c \u0627\u0648\u0631\u064a\u0644\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:400\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0628\u064a\u0627\u0646\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-key=\"ad63541d4f\" data-product-id=\"25575\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25575\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25575\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25575\" data-product_sku=\"9789775239938\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;1984&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;1984&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25575\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25575\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-24607 status-publish first instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"4\" data-id=\"24607\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-id=\"24607\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\">200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>11&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u062d\u0627\u0641\u0638 \u0628\u0646 \u0623\u062d\u0645\u062f \u062d\u0643\u0645\u0649\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:159\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0641\u0636\u064a\u0644\u0629\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-key=\"ad63541d4f\" data-product-id=\"24607\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24607\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24607\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24607\" data-product_sku=\"9772972298\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24607\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24607\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-27450 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"27450\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-id=\"27450\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\">Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthors: Sulaiman Ismail &amp; Yuslina Mohamed\r\nNumber of Pages: 153\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-key=\"ad63541d4f\" data-product-id=\"27450\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27450\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27450\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27450\" data-product_sku=\"MashreqPub1\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27450\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27450\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-24896 status-publish instock product_cat-811 has-post-thumbnail purchasable product-type-simple\" data-loop=\"6\" data-id=\"24896\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" data-id=\"13596\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\">Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>60&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641: \u0645\u062e\u062a\u0627\u0631 \u0627\u0644\u0637\u0627\u0647\u0631 \u062d\u0633\u064a\u0646\r\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a: 195\r\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0643\u062a\u0627\u0628 \u0645\u0639 CD\r\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\r\n\u0627\u0644\u0646\u0627\u0634\u0631: \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0644\u0644\u062c\u0645\u064a\u0639\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" data-key=\"ad63541d4f\" data-product-id=\"13596\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24896\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24896\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24896\" data-product_sku=\"Child1160\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24896\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24896\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-27451 status-publish last instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"27451\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Beyond Borders &#8211; Circular Economy And Marketing\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" data-id=\"27451\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\">Beyond Borders &#8211; Circular Economy And Marketing<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Muhammad Tahir\r\nNumber of Pages: 128\r\nCover Type: Hardcover\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" data-key=\"ad63541d4f\" data-product-id=\"27451\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27451\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27451\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27451\" data-product_sku=\"MashreqPub2\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Beyond Borders - Circular Economy And Marketing&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Beyond Borders - Circular Economy And Marketing&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27451\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27451\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-27452 status-publish first instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"27452\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" data-id=\"27452\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\">Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>28&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Ali Ali Gobaili Saged\r\nNumber of Pages: 130\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" data-key=\"ad63541d4f\" data-product-id=\"27452\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27452\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27452\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27452\" data-product_sku=\"MashreqPub3\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27452\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27452\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-ajax-arrows wd-hover-1 wd-pos-sep wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner  wd-role-btn\" tabindex=\"0\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner  wd-role-btn\" tabindex=\"0\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t[\/vc_column][\/vc_row][vc_row][vc_column]\n\t\t<div id=\"wd-61f2512610d3d\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-61f2512610d3d wd-title-color-default wd-title-style-default text-center vc_custom_1643270463142 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xl\" >\u0627\u062e\u062a\u0631\u0646\u0627 \u0644\u0643<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"title-after_title reset-last-child  wd-fontsize-s\">\u0645\u062c\u0645\u0648\u0639\u0629 \u0645\u062a\u0646\u0648\u0639\u0629 \u0645\u0646 \u0627\u062d\u062f\u062b \u0627\u0644\u0627\u0635\u062f\u0627\u0631\u0627\u062a<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t[\/vc_column][vc_column width=&#8221;1\/2&#8243;]\n\t\t<div id=\"wd-61f25195918ea\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-61f25195918ea wd-title-color-primary wd-title-style-underlined text-right vc_custom_1643270555297 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >\u0627\u0644\u0627\u0639\u0644\u064a \u0645\u0628\u064a\u0639\u0627<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t\t<div id=\"\" class=\"wd-products-element wd-wpb\">\n\t\t\t\n\t\t\n\t\t\t\t\t<div class=\"products wd-products  grid-columns-4 elements-grid wd-grid-g\" data-paged=\"1\" data-atts=\"{&quot;items_per_page&quot;:&quot;&quot;,&quot;product_hover&quot;:&quot;quick&quot;,&quot;columns&quot;:&quot;4&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;highlighted_products&quot;:&quot;0&quot;,&quot;products_bordered_grid&quot;:&quot;0&quot;,&quot;img_size&quot;:&quot;320x295&quot;,&quot;force_not_ajax&quot;:&quot;no&quot;}\" data-source=\"shortcode\" data-columns=\"4\" data-grid-gallery=\"\" style=\"--wd-col-lg:4;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:30px;--wd-gap-sm:10px;\">\n\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-27601 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"27601\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"295\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-scaled-320x295.jpg\" class=\"attachment-320x295 size-320x295\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-id=\"27601\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27601\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-key=\"ad63541d4f\" data-product-id=\"27601\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27601\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27601\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27601\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27601\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\">(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>85&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-25672 status-publish instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"2\" data-id=\"25672\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"295\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-320x295.jpg\" class=\"attachment-320x295 size-320x295\" alt=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-id=\"25672\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25672\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-key=\"ad63541d4f\" data-product-id=\"25672\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25672\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25672\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25672\" data-product_sku=\"MASHCODE142\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25672\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\">11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>15&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-25575 status-publish last instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"3\" data-id=\"25575\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"1984\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"295\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-320x295.jpg\" class=\"attachment-320x295 size-320x295\" alt=\"1984\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-id=\"25575\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25575\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-key=\"ad63541d4f\" data-product-id=\"25575\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25575\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25575\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25575\" data-product_sku=\"9789775239938\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;1984&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;1984&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25575\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\">1984<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-24607 status-publish first instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"4\" data-id=\"24607\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"295\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-320x295.jpg\" class=\"attachment-320x295 size-320x295\" alt=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-id=\"24607\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24607\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-key=\"ad63541d4f\" data-product-id=\"24607\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24607\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24607\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24607\" data-product_sku=\"9772972298\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24607\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\">200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>11&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-27450 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"27450\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"295\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-320x295.jpg\" class=\"attachment-320x295 size-320x295\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-id=\"27450\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27450\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-key=\"ad63541d4f\" data-product-id=\"27450\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27450\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27450\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27450\" data-product_sku=\"MashreqPub1\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27450\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\">Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-24896 status-publish instock product_cat-811 has-post-thumbnail purchasable product-type-simple\" data-loop=\"6\" data-id=\"24896\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"295\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-320x295.jpg\" class=\"attachment-320x295 size-320x295\" alt=\"Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" data-id=\"13596\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24896\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" data-key=\"ad63541d4f\" data-product-id=\"13596\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24896\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24896\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24896\" data-product_sku=\"Child1160\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24896\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\">Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>60&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-27451 status-publish last instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"27451\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Beyond Borders &#8211; Circular Economy And Marketing\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"295\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-320x295.jpg\" class=\"attachment-320x295 size-320x295\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" data-id=\"27451\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27451\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" data-key=\"ad63541d4f\" data-product-id=\"27451\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27451\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27451\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27451\" data-product_sku=\"MashreqPub2\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Beyond Borders - Circular Economy And Marketing&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Beyond Borders - Circular Economy And Marketing&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27451\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\">Beyond Borders &#8211; Circular Economy And Marketing<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-27452 status-publish first instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"27452\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"295\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-320x295.jpg\" class=\"attachment-320x295 size-320x295\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" data-id=\"27452\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27452\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" data-key=\"ad63541d4f\" data-product-id=\"27452\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27452\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27452\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27452\" data-product_sku=\"MashreqPub3\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27452\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\">Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>28&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-27453 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"9\" data-id=\"27453\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Humanizing Science Education &#8211; STS as a Model\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"295\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-320x295.jpg\" class=\"attachment-320x295 size-320x295\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" data-id=\"27453\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27453\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" data-key=\"ad63541d4f\" data-product-id=\"27453\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27453\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27453\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27453\" data-product_sku=\"MashreqPub4\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Humanizing Science Education - STS as a Model&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Humanizing Science Education - STS as a Model&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27453\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\">Humanizing Science Education &#8211; STS as a Model<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-27454 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"10\" data-id=\"27454\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Influence of Media on People and Society\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"295\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-320x295.jpg\" class=\"attachment-320x295 size-320x295\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" data-id=\"27454\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27454\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" data-key=\"ad63541d4f\" data-product-id=\"27454\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27454\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27454\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27454\" data-product_sku=\"MashreqPub5\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Influence of Media on People and Society&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Influence of Media on People and Society&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27454\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\">Influence of Media on People and Society<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243;]\t\t\t\n\t\t\t<div id=\"carousel-216\" class=\"wd-carousel-container  wd-wpb wd-highlighted-products with-title  wd-products-element wd-products products\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h4 class=\"wd-el-title title slider-title element-title\"><span>\u0643\u062a\u0628 \u0645\u0645\u064a\u0632\u0629<\/span><\/h4>\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t<div class=\" wd-carousel wd-grid scroll-init\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:1;--wd-col-md:1;--wd-col-sm:1;\">\n\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-27601 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"27601\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"387\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-scaled-339x387.jpg\" class=\"attachment-339x387 size-339x387\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-id=\"27601\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27601\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-key=\"ad63541d4f\" data-product-id=\"27601\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27601\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27601\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27601\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27601\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\">(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>85&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-25672 status-publish instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"2\" data-id=\"25672\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"387\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-339x387.jpg\" class=\"attachment-339x387 size-339x387\" alt=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-id=\"25672\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25672\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-key=\"ad63541d4f\" data-product-id=\"25672\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25672\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25672\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25672\" data-product_sku=\"MASHCODE142\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25672\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\">11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>15&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-25575 status-publish last instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"3\" data-id=\"25575\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"1984\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"387\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-339x387.jpg\" class=\"attachment-339x387 size-339x387\" alt=\"1984\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-id=\"25575\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25575\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-key=\"ad63541d4f\" data-product-id=\"25575\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25575\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25575\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25575\" data-product_sku=\"9789775239938\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;1984&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;1984&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25575\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\">1984<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-24607 status-publish first instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"4\" data-id=\"24607\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"387\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-339x387.jpg\" class=\"attachment-339x387 size-339x387\" alt=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-id=\"24607\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24607\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-key=\"ad63541d4f\" data-product-id=\"24607\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24607\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24607\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24607\" data-product_sku=\"9772972298\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24607\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\">200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>11&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-27450 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"27450\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"387\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-339x387.jpg\" class=\"attachment-339x387 size-339x387\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-id=\"27450\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27450\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-key=\"ad63541d4f\" data-product-id=\"27450\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27450\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27450\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27450\" data-product_sku=\"MashreqPub1\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27450\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\">Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-together wd-custom-style wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t[\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;100px&#8221; woodmart_hide_large=&#8221;0&#8243; woodmart_hide_medium=&#8221;0&#8243; woodmart_hide_small=&#8221;0&#8243; woodmart_hide_extra_small=&#8221;0&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;]\t\t\t\n\t\t\t<div id=\"carousel-710\" class=\"wd-carousel-container  wd-wpb wd-highlighted-products with-title  wd-products-element wd-products products\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h4 class=\"wd-el-title title slider-title element-title\"><span>\u0643\u062a\u0628 \u0645\u062e\u0641\u0636\u0629<\/span><\/h4>\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t<div class=\" wd-carousel wd-grid scroll-init\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:1;--wd-col-md:1;--wd-col-sm:1;\">\n\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-27601 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"27601\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"387\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-scaled-339x387.jpg\" class=\"attachment-339x387 size-339x387\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-id=\"27601\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27601\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-key=\"ad63541d4f\" data-product-id=\"27601\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27601\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27601\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27601\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27601\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\">(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>85&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-25672 status-publish instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"2\" data-id=\"25672\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"387\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-339x387.jpg\" class=\"attachment-339x387 size-339x387\" alt=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-id=\"25672\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25672\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-key=\"ad63541d4f\" data-product-id=\"25672\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25672\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25672\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25672\" data-product_sku=\"MASHCODE142\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25672\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\">11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>15&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-25575 status-publish last instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"3\" data-id=\"25575\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"1984\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"387\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-339x387.jpg\" class=\"attachment-339x387 size-339x387\" alt=\"1984\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-id=\"25575\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25575\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-key=\"ad63541d4f\" data-product-id=\"25575\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25575\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25575\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25575\" data-product_sku=\"9789775239938\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;1984&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;1984&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25575\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\">1984<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-24607 status-publish first instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"4\" data-id=\"24607\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"387\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-339x387.jpg\" class=\"attachment-339x387 size-339x387\" alt=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-id=\"24607\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24607\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-key=\"ad63541d4f\" data-product-id=\"24607\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24607\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24607\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24607\" data-product_sku=\"9772972298\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24607\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\">200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>11&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-27450 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"27450\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"387\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-339x387.jpg\" class=\"attachment-339x387 size-339x387\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-id=\"27450\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27450\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-key=\"ad63541d4f\" data-product-id=\"27450\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27450\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27450\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27450\" data-product_sku=\"MashreqPub1\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27450\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\">Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-together wd-custom-style wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t[\/vc_column][vc_column width=&#8221;1\/2&#8243;]\n\t\t<div id=\"wd-61f251d62d37b\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-61f251d62d37b wd-title-color-primary wd-title-style-underlined text-right vc_custom_1643270621474 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >\u0643\u062a\u0628 \u0645\u0645\u064a\u0632\u0629<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t\t<div id=\"\" class=\"wd-products-element wd-wpb\">\n\t\t\t\n\t\t\n\t\t\t\t\t<div class=\"products wd-products  grid-columns-4 elements-grid wd-grid-g\" data-paged=\"1\" data-atts=\"{&quot;items_per_page&quot;:&quot;&quot;,&quot;product_hover&quot;:&quot;quick&quot;,&quot;columns&quot;:&quot;4&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;highlighted_products&quot;:&quot;0&quot;,&quot;products_bordered_grid&quot;:&quot;0&quot;,&quot;img_size&quot;:&quot;320x295&quot;,&quot;force_not_ajax&quot;:&quot;no&quot;}\" data-source=\"shortcode\" data-columns=\"4\" data-grid-gallery=\"\" style=\"--wd-col-lg:4;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:30px;--wd-gap-sm:10px;\">\n\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-27601 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"27601\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"295\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-scaled-320x295.jpg\" class=\"attachment-320x295 size-320x295\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-id=\"27601\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27601\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-key=\"ad63541d4f\" data-product-id=\"27601\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27601\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27601\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27601\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27601\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\">(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>85&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-25672 status-publish instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"2\" data-id=\"25672\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"295\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-320x295.jpg\" class=\"attachment-320x295 size-320x295\" alt=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-id=\"25672\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25672\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-key=\"ad63541d4f\" data-product-id=\"25672\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25672\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25672\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25672\" data-product_sku=\"MASHCODE142\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25672\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\">11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>15&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-25575 status-publish last instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"3\" data-id=\"25575\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"1984\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"295\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-320x295.jpg\" class=\"attachment-320x295 size-320x295\" alt=\"1984\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-id=\"25575\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25575\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-key=\"ad63541d4f\" data-product-id=\"25575\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25575\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25575\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25575\" data-product_sku=\"9789775239938\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;1984&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;1984&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25575\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\">1984<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-24607 status-publish first instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"4\" data-id=\"24607\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"295\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-320x295.jpg\" class=\"attachment-320x295 size-320x295\" alt=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-id=\"24607\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24607\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-key=\"ad63541d4f\" data-product-id=\"24607\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24607\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24607\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24607\" data-product_sku=\"9772972298\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24607\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\">200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>11&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-27450 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"27450\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"295\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-320x295.jpg\" class=\"attachment-320x295 size-320x295\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-id=\"27450\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27450\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-key=\"ad63541d4f\" data-product-id=\"27450\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27450\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27450\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27450\" data-product_sku=\"MashreqPub1\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27450\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\">Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-24896 status-publish instock product_cat-811 has-post-thumbnail purchasable product-type-simple\" data-loop=\"6\" data-id=\"24896\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"295\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-320x295.jpg\" class=\"attachment-320x295 size-320x295\" alt=\"Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" data-id=\"13596\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24896\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" data-key=\"ad63541d4f\" data-product-id=\"13596\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24896\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24896\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24896\" data-product_sku=\"Child1160\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24896\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\">Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>60&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-27451 status-publish last instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"27451\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Beyond Borders &#8211; Circular Economy And Marketing\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"295\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-320x295.jpg\" class=\"attachment-320x295 size-320x295\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" data-id=\"27451\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27451\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" data-key=\"ad63541d4f\" data-product-id=\"27451\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27451\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27451\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27451\" data-product_sku=\"MashreqPub2\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Beyond Borders - Circular Economy And Marketing&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Beyond Borders - Circular Economy And Marketing&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27451\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\">Beyond Borders &#8211; Circular Economy And Marketing<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-27452 status-publish first instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"27452\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"295\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-320x295.jpg\" class=\"attachment-320x295 size-320x295\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" data-id=\"27452\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27452\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" data-key=\"ad63541d4f\" data-product-id=\"27452\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27452\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27452\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27452\" data-product_sku=\"MashreqPub3\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27452\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\">Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>28&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-27453 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"9\" data-id=\"27453\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Humanizing Science Education &#8211; STS as a Model\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"295\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-320x295.jpg\" class=\"attachment-320x295 size-320x295\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" data-id=\"27453\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27453\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" data-key=\"ad63541d4f\" data-product-id=\"27453\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27453\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27453\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27453\" data-product_sku=\"MashreqPub4\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Humanizing Science Education - STS as a Model&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Humanizing Science Education - STS as a Model&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27453\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\">Humanizing Science Education &#8211; STS as a Model<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-27454 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"10\" data-id=\"27454\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Influence of Media on People and Society\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"295\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-320x295.jpg\" class=\"attachment-320x295 size-320x295\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" data-id=\"27454\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27454\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" data-key=\"ad63541d4f\" data-product-id=\"27454\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27454\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27454\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27454\" data-product_sku=\"MashreqPub5\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Influence of Media on People and Society&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Influence of Media on People and Society&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27454\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\">Influence of Media on People and Society<\/a><\/h3>\n\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>[\/vc_column][\/vc_row][vc_row woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243; woodmart_disable_overflow=&#8221;0&#8243;][vc_column css=&#8221;.vc_custom_1541507763869{padding-top: 0px !important;}&#8221; woodmart_parallax=&#8221;0&#8243; parallax_scroll=&#8221;no&#8221; woodmart_sticky_column=&#8221;false&#8221;]\n\t\t<div id=\"wd-61f2525f304d0\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-61f2525f304d0 wd-title-color-primary wd-title-style-underlined text-right wd-off-anim wpb_animate_when_almost_visible wpb_fadeInDown fadeInDown wd-anim-name_fadeInDown  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xl\" >\u0627\u062d\u062f\u062b \u0627\u0644\u0627\u0635\u062f\u0627\u0631\u0627\u062a<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t\t\n\t\t\t<div id=\"carousel-384\" class=\"wd-carousel-container  wd-wpb  wd-products-element wd-products products products-bordered-grid\">\n\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t<div class=\" wd-carousel wd-grid\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:4;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:30px;--wd-gap-sm:10px;\">\n\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27601 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"27601\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-scaled-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-scaled-174x174.jpg 174w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-400x400.jpg 400w\" sizes=\"auto, (max-width: 174px) 100vw, 174px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-id=\"27601\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\">(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>85&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0633\u0645 \u0627\u0644\u0643\u062a\u0627\u0628: \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u0651\u064e\u062d\u0652\u0648\u061f\r\n\u0627\u0644\u0645\u0624\u0644\u0641: \u0623\u062d\u0645\u062f \u0625\u0633\u0643\u0646\u062f\u0631.\r\n\u0627\u0644\u0646\u0627\u0634\u0631: \u062f\u0627\u0631 \u0627\u0644\u0644\u0624\u0644\u0624\u0629 \u0644\u0644\u0646\u0634\u0631 \u0648\u0627\u0644\u062a\u0648\u0632\u064a\u0639 (\u0627\u0644\u0645\u0646\u0635\u0648\u0631\u0629 - \u0645\u0635\u0631).\r\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629: \u0627\u0644\u0637\u0628\u0639\u0629 \u0627\u0644\u062a\u0627\u0633\u0639\u0629 \u0639\u0634\u0631\u0629 (2024 \u0645 - 1445 \u0647\u0640).\r\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641: \u063a\u0644\u0627\u0641 \u0648\u0631\u0642\u064a \u0639\u0627\u062f\u064a (Paperback).\r\n\u0631\u0642\u0645 \u0627\u0644\u0625\u064a\u062f\u0627\u0639: 4153 \/ 2022 \u0645.\r\n\r\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a: 552\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-key=\"ad63541d4f\" data-product-id=\"27601\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27601\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27601\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27601\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27601\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27601\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-25672 status-publish instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"2\" data-id=\"25672\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-id=\"25672\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\">11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>15&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u0639\u0635\u0627\u0645 \u0645\u0646\u0635\u0648\u0631\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:172\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0634\u0631\u0648\u0642\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-key=\"ad63541d4f\" data-product-id=\"25672\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25672\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25672\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25672\" data-product_sku=\"MASHCODE142\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25672\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25672\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-25575 status-publish last instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"3\" data-id=\"25575\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"1984\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"1984\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-id=\"25575\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\">1984<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u062c\u0648\u0631\u062c \u0627\u0648\u0631\u064a\u0644\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:400\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0628\u064a\u0627\u0646\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-key=\"ad63541d4f\" data-product-id=\"25575\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25575\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25575\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25575\" data-product_sku=\"9789775239938\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;1984&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;1984&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25575\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25575\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-24607 status-publish first instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"4\" data-id=\"24607\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-id=\"24607\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\">200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>11&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u062d\u0627\u0641\u0638 \u0628\u0646 \u0623\u062d\u0645\u062f \u062d\u0643\u0645\u0649\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:159\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0641\u0636\u064a\u0644\u0629\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-key=\"ad63541d4f\" data-product-id=\"24607\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24607\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24607\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24607\" data-product_sku=\"9772972298\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24607\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24607\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27450 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"27450\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-174x174.jpg 174w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-400x400.jpg 400w\" sizes=\"auto, (max-width: 174px) 100vw, 174px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-id=\"27450\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\">Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthors: Sulaiman Ismail &amp; Yuslina Mohamed\r\nNumber of Pages: 153\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-key=\"ad63541d4f\" data-product-id=\"27450\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27450\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27450\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27450\" data-product_sku=\"MashreqPub1\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27450\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27450\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-24896 status-publish instock product_cat-811 has-post-thumbnail purchasable product-type-simple\" data-loop=\"6\" data-id=\"24896\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" data-id=\"13596\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\">Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>60&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641: \u0645\u062e\u062a\u0627\u0631 \u0627\u0644\u0637\u0627\u0647\u0631 \u062d\u0633\u064a\u0646\r\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a: 195\r\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0643\u062a\u0627\u0628 \u0645\u0639 CD\r\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\r\n\u0627\u0644\u0646\u0627\u0634\u0631: \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0644\u0644\u062c\u0645\u064a\u0639\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" data-key=\"ad63541d4f\" data-product-id=\"13596\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24896\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24896\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24896\" data-product_sku=\"Child1160\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24896\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24896\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27451 status-publish last instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"27451\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Beyond Borders &#8211; Circular Economy And Marketing\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-174x174.jpg 174w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-400x400.jpg 400w\" sizes=\"auto, (max-width: 174px) 100vw, 174px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" data-id=\"27451\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\">Beyond Borders &#8211; Circular Economy And Marketing<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Muhammad Tahir\r\nNumber of Pages: 128\r\nCover Type: Hardcover\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" data-key=\"ad63541d4f\" data-product-id=\"27451\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27451\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27451\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27451\" data-product_sku=\"MashreqPub2\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Beyond Borders - Circular Economy And Marketing&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Beyond Borders - Circular Economy And Marketing&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27451\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27451\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27452 status-publish first instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"27452\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" data-id=\"27452\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\">Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>28&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Ali Ali Gobaili Saged\r\nNumber of Pages: 130\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" data-key=\"ad63541d4f\" data-product-id=\"27452\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27452\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27452\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27452\" data-product_sku=\"MashreqPub3\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27452\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27452\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27453 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"9\" data-id=\"27453\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Humanizing Science Education &#8211; STS as a Model\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-174x174.jpg 174w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-400x400.jpg 400w\" sizes=\"auto, (max-width: 174px) 100vw, 174px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" data-id=\"27453\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\">Humanizing Science Education &#8211; STS as a Model<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Muhammad Yusuf\r\nNumber of Pages: 146\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" data-key=\"ad63541d4f\" data-product-id=\"27453\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27453\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27453\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27453\" data-product_sku=\"MashreqPub4\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Humanizing Science Education - STS as a Model&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Humanizing Science Education - STS as a Model&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27453\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27453\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27454 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"10\" data-id=\"27454\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Influence of Media on People and Society\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-174x174.jpg 174w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-400x400.jpg 400w\" sizes=\"auto, (max-width: 174px) 100vw, 174px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" data-id=\"27454\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\">Influence of Media on People and Society<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Ahmed Abdel-Malik\r\nNumber of Pages: 123\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" data-key=\"ad63541d4f\" data-product-id=\"27454\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27454\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27454\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27454\" data-product_sku=\"MashreqPub5\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Influence of Media on People and Society&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Influence of Media on People and Society&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27454\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27454\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"wd-nav-pagin-wrap text-center wd-style-shape wd-hide-md-sm wd-hide-sm\">\n\t\t\t<ul class=\"wd-nav-pagin\"><\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1635923002079{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243; woodmart_disable_overflow=&#8221;0&#8243; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221;][vc_column css=&#8221;.vc_custom_1495003905736{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;]\n\t\t<div id=\"wd-5e5df43c6ded7\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5e5df43c6ded7 wd-title-color-default wd-title-style-default text-center wd-off-anim wpb_animate_when_almost_visible wpb_fadeInDown fadeInDown wd-anim-name_fadeInDown vc_custom_1583215690007 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xl\" >Latest BOOKS<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t\t\n\t\t\t<div id=\"carousel-734\" class=\"wd-carousel-container  wd-wpb  wd-products-element wd-products products\">\n\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t<div class=\" wd-carousel wd-grid scroll-init\" data-speed=\"5000\" data-wrap=\"yes\" data-autoplay=\"yes\" data-scroll_per_page=\"yes\" data-center_mode=\"yes\" style=\"--wd-col-lg:5;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27601 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"27601\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-scaled-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-id=\"27601\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\">(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>85&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0633\u0645 \u0627\u0644\u0643\u062a\u0627\u0628: \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u0651\u064e\u062d\u0652\u0648\u061f\r\n\u0627\u0644\u0645\u0624\u0644\u0641: \u0623\u062d\u0645\u062f \u0625\u0633\u0643\u0646\u062f\u0631.\r\n\u0627\u0644\u0646\u0627\u0634\u0631: \u062f\u0627\u0631 \u0627\u0644\u0644\u0624\u0644\u0624\u0629 \u0644\u0644\u0646\u0634\u0631 \u0648\u0627\u0644\u062a\u0648\u0632\u064a\u0639 (\u0627\u0644\u0645\u0646\u0635\u0648\u0631\u0629 - \u0645\u0635\u0631).\r\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629: \u0627\u0644\u0637\u0628\u0639\u0629 \u0627\u0644\u062a\u0627\u0633\u0639\u0629 \u0639\u0634\u0631\u0629 (2024 \u0645 - 1445 \u0647\u0640).\r\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641: \u063a\u0644\u0627\u0641 \u0648\u0631\u0642\u064a \u0639\u0627\u062f\u064a (Paperback).\r\n\u0631\u0642\u0645 \u0627\u0644\u0625\u064a\u062f\u0627\u0639: 4153 \/ 2022 \u0645.\r\n\r\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a: 552\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-key=\"ad63541d4f\" data-product-id=\"27601\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27601\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27601\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27601\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27601\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27601\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-25672 status-publish instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"2\" data-id=\"25672\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-id=\"25672\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\">11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>15&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u0639\u0635\u0627\u0645 \u0645\u0646\u0635\u0648\u0631\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:172\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0634\u0631\u0648\u0642\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-key=\"ad63541d4f\" data-product-id=\"25672\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25672\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25672\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25672\" data-product_sku=\"MASHCODE142\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25672\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25672\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-25575 status-publish last instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"3\" data-id=\"25575\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"1984\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"1984\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-id=\"25575\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\">1984<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u062c\u0648\u0631\u062c \u0627\u0648\u0631\u064a\u0644\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:400\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0628\u064a\u0627\u0646\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-key=\"ad63541d4f\" data-product-id=\"25575\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25575\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25575\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25575\" data-product_sku=\"9789775239938\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;1984&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;1984&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25575\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25575\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-24607 status-publish first instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"4\" data-id=\"24607\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-id=\"24607\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\">200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>11&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u062d\u0627\u0641\u0638 \u0628\u0646 \u0623\u062d\u0645\u062f \u062d\u0643\u0645\u0649\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:159\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0641\u0636\u064a\u0644\u0629\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-key=\"ad63541d4f\" data-product-id=\"24607\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24607\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24607\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24607\" data-product_sku=\"9772972298\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24607\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24607\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27450 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"27450\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-id=\"27450\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\">Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthors: Sulaiman Ismail &amp; Yuslina Mohamed\r\nNumber of Pages: 153\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-key=\"ad63541d4f\" data-product-id=\"27450\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27450\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27450\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27450\" data-product_sku=\"MashreqPub1\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27450\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27450\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-24896 status-publish instock product_cat-811 has-post-thumbnail purchasable product-type-simple\" data-loop=\"6\" data-id=\"24896\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" data-id=\"13596\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\">Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>60&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641: \u0645\u062e\u062a\u0627\u0631 \u0627\u0644\u0637\u0627\u0647\u0631 \u062d\u0633\u064a\u0646\r\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a: 195\r\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0643\u062a\u0627\u0628 \u0645\u0639 CD\r\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\r\n\u0627\u0644\u0646\u0627\u0634\u0631: \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0644\u0644\u062c\u0645\u064a\u0639\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" data-key=\"ad63541d4f\" data-product-id=\"13596\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24896\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24896\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24896\" data-product_sku=\"Child1160\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24896\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24896\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27451 status-publish last instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"27451\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Beyond Borders &#8211; Circular Economy And Marketing\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" data-id=\"27451\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\">Beyond Borders &#8211; Circular Economy And Marketing<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Muhammad Tahir\r\nNumber of Pages: 128\r\nCover Type: Hardcover\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" data-key=\"ad63541d4f\" data-product-id=\"27451\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27451\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27451\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27451\" data-product_sku=\"MashreqPub2\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Beyond Borders - Circular Economy And Marketing&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Beyond Borders - Circular Economy And Marketing&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27451\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27451\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27452 status-publish first instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"27452\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" data-id=\"27452\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\">Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>28&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Ali Ali Gobaili Saged\r\nNumber of Pages: 130\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" data-key=\"ad63541d4f\" data-product-id=\"27452\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27452\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27452\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27452\" data-product_sku=\"MashreqPub3\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27452\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27452\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27453 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"9\" data-id=\"27453\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Humanizing Science Education &#8211; STS as a Model\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" data-id=\"27453\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\">Humanizing Science Education &#8211; STS as a Model<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Muhammad Yusuf\r\nNumber of Pages: 146\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" data-key=\"ad63541d4f\" data-product-id=\"27453\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27453\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27453\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27453\" data-product_sku=\"MashreqPub4\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Humanizing Science Education - STS as a Model&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Humanizing Science Education - STS as a Model&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27453\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27453\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27454 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"10\" data-id=\"27454\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Influence of Media on People and Society\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" data-id=\"27454\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\">Influence of Media on People and Society<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Ahmed Abdel-Malik\r\nNumber of Pages: 123\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" data-key=\"ad63541d4f\" data-product-id=\"27454\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27454\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27454\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27454\" data-product_sku=\"MashreqPub5\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Influence of Media on People and Society&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Influence of Media on People and Society&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27454\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27454\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27455 status-publish last instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"11\" data-id=\"27455\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-1\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Islamic Studies Book 1\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-1\/\" data-id=\"27455\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-1\/\">Islamic Studies Book 1<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>50&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Imam Nurdin Muhammad Ali\r\nNumber of Pages: 137\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-1\/\" data-key=\"ad63541d4f\" data-product-id=\"27455\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27455\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27455\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27455\" data-product_sku=\"MashreqPub6\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Islamic Studies Book 1&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Islamic Studies Book 1&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27455\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-1\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27455\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27456 status-publish first instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"12\" data-id=\"27456\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-2\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Islamic Studies Book 2\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-2\/\" data-id=\"27456\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-2\/\">Islamic Studies Book 2<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>50&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Imam Nurdin Muhammad Ali\r\nNumber of Pages: 132\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Dar Al-Mashreq International Book House\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-2\/\" data-key=\"ad63541d4f\" data-product-id=\"27456\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27456\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27456\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27456\" data-product_sku=\"MashreqPub7\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Islamic Studies Book 2&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Islamic Studies Book 2&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27456\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-2\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27456\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"wd-nav-pagin-wrap text-center wd-style-shape wd-hide-md-sm wd-hide-sm\">\n\t\t\t<ul class=\"wd-nav-pagin\"><\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1523621161048{margin-top: -40px !important;}&#8221;][vc_column css_animation=&#8221;fadeIn&#8221; width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1635921784885{padding-top: 8vh !important;padding-right: 8vh !important;padding-bottom: 8vh !important;padding-left: 8vh !important;background-image: url(https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/03\/\u0641\u0642\u0647-\u0627\u0644\u0633\u0646\u0629-5.jpg?id=6307) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: contain !important;}&#8221; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_sticky_column=&#8221;false&#8221; parallax_scroll=&#8221;no&#8221; mobile_reset_margin=&#8221;no&#8221; tablet_reset_margin=&#8221;no&#8221;][vc_single_image image=&#8221;3204&#8243; img_size=&#8221;385&#215;480&#8243; alignment=&#8221;right&#8221; style=&#8221;vc_box_shadow_3d&#8221; css_animation=&#8221;fadeInUp&#8221; scroll_x=&#8221;0&#8243; scroll_y=&#8221;-40&#8243; scroll_z=&#8221;0&#8243; parallax_scroll=&#8221;yes&#8221; css=&#8221;.vc_custom_1583218673238{margin-right: -160px !important;margin-bottom: 0px !important;padding-top: 4vh !important;padding-bottom: 4vh !important;}&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; scroll_x=&#8221;0&#8243; scroll_y=&#8221;30&#8243; scroll_z=&#8221;0&#8243; parallax_scroll=&#8221;yes&#8221; css=&#8221;.vc_custom_1525683911075{padding-top: 5vh !important;padding-right: 15% !important;padding-bottom: 5vh !important;padding-left: 15% !important;}&#8221;]\t\t\t<div id=\"wd-61f25383bb099\" class=\"wd-text-block-wrapper wd-wpb wd-rs-61f25383bb099 color-scheme-custom text-left vc_custom_1643271049482\">\n\t\t\t\t<div class=\"woodmart-title-container woodmart-text-block reset-last-child font-alt wd-font-weight-400 \">\n\t\t\t\t\t<\/p>\n<p style=\"text-align: right;\">\u0627\u0644\u0627\u0639\u0644\u064a \u0645\u0628\u064a\u0639\u0627<\/p>\n<p>\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"wd-61f2538ec6718\" class=\"wd-text-block-wrapper wd-wpb wd-rs-61f2538ec6718 color-scheme-dark text-left vc_custom_1643271062672\">\n\t\t\t\t<div class=\"woodmart-title-container woodmart-text-block reset-last-child font-primary wd-font-weight-400 \">\n\t\t\t\t\t<\/p>\n<p style=\"text-align: right;\">\u0641\u0642\u0629 \u0627\u0644\u0633\u0646\u0629<\/p>\n<p style=\"text-align: right;\">\u0627\u0644\u0633\u064a\u062f \u0633\u0627\u0628\u0642<\/p>\n<p>\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"wd-61f2539ca885c\" class=\"wd-text-block-wrapper wd-wpb wd-rs-61f2539ca885c color-scheme- text-left wd-width-enabled vc_custom_1643271073573\" style=\"--wd-max-width: 80%;\">\n\t\t\t\t<div class=\"woodmart-title-container woodmart-text-block reset-last-child font-text wd-font-weight-400 \">\n\t\t\t\t\t<\/p>\n<p style=\"text-align: right;\">\u0648\u0627\u062d\u062f \u0645\u0646 \u0627\u0641\u0636\u0644 \u0627\u0644\u0643\u062a\u0628 \u0627\u0644\u0641\u0642\u0647\u064a\u0629 \u0641\u064a \u0641\u0642\u0647 \u0627\u0644\u0633\u0646\u0647<\/p>\n<p>\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<div id=\"wd-61f252d2d9b86\" class=\" wd-rs-61f252d2d9b86  wd-button-wrapper text-center inline-element\"><a href=\"https:\/\/mashreq.com.my\/en\/books\/%d9%81%d9%82%d9%87-%d8%a7%d9%84%d8%b3%d9%86%d8%a9\/\" title=\"\u0641\u0642\u0647 \u0627\u0644\u0633\u0646\u0629\" class=\"btn btn-color-black btn-style-default btn-shape-round btn-size-default\">\u0627\u0644\u0645\u0632\u064a\u062f \u0644\u0644\u0643\u0627\u062a\u0628<\/a><\/div><div id=\"wd-61f252e645354\" class=\" wd-rs-61f252e645354  wd-button-wrapper text-center inline-element\"><a href=\"https:\/\/mashreq.com.my\/en\/books\/%d9%81%d9%82%d9%87-%d8%a7%d9%84%d8%b3%d9%86%d8%a9\/\" title=\"\u0641\u0642\u0647 \u0627\u0644\u0633\u0646\u0629\" class=\"btn btn-style-bordered btn-shape-round btn-size-default\">\u0623\u0634\u062a\u0631\u064a \u0627\u0644\u0627\u0646<\/a><\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1635923201322{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243; woodmart_disable_overflow=&#8221;0&#8243; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221;][vc_column css=&#8221;.vc_custom_1495003905736{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;]\n\t\t<div id=\"wd-5e5e05948dd80\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5e5e05948dd80 wd-title-color-default wd-title-style-default text-center wd-off-anim wpb_animate_when_almost_visible wpb_fadeInDown fadeInDown wd-anim-name_fadeInDown vc_custom_1583220179960 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xl\" >Arabic Collection<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t\t\n\t\t\t<div id=\"carousel-871\" class=\"wd-carousel-container  wd-wpb  wd-products-element wd-products products\">\n\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t<div class=\" wd-carousel wd-grid\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:4;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27601 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"27601\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-scaled-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-id=\"27601\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\">(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>85&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0633\u0645 \u0627\u0644\u0643\u062a\u0627\u0628: \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u0651\u064e\u062d\u0652\u0648\u061f\r\n\u0627\u0644\u0645\u0624\u0644\u0641: \u0623\u062d\u0645\u062f \u0625\u0633\u0643\u0646\u062f\u0631.\r\n\u0627\u0644\u0646\u0627\u0634\u0631: \u062f\u0627\u0631 \u0627\u0644\u0644\u0624\u0644\u0624\u0629 \u0644\u0644\u0646\u0634\u0631 \u0648\u0627\u0644\u062a\u0648\u0632\u064a\u0639 (\u0627\u0644\u0645\u0646\u0635\u0648\u0631\u0629 - \u0645\u0635\u0631).\r\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629: \u0627\u0644\u0637\u0628\u0639\u0629 \u0627\u0644\u062a\u0627\u0633\u0639\u0629 \u0639\u0634\u0631\u0629 (2024 \u0645 - 1445 \u0647\u0640).\r\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641: \u063a\u0644\u0627\u0641 \u0648\u0631\u0642\u064a \u0639\u0627\u062f\u064a (Paperback).\r\n\u0631\u0642\u0645 \u0627\u0644\u0625\u064a\u062f\u0627\u0639: 4153 \/ 2022 \u0645.\r\n\r\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a: 552\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-key=\"ad63541d4f\" data-product-id=\"27601\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27601\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27601\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27601\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27601\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27601\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-25672 status-publish instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"2\" data-id=\"25672\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-id=\"25672\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\">11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>15&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u0639\u0635\u0627\u0645 \u0645\u0646\u0635\u0648\u0631\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:172\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0634\u0631\u0648\u0642\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-key=\"ad63541d4f\" data-product-id=\"25672\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25672\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25672\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25672\" data-product_sku=\"MASHCODE142\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25672\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25672\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-25575 status-publish last instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"3\" data-id=\"25575\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"1984\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"1984\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-id=\"25575\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\">1984<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u062c\u0648\u0631\u062c \u0627\u0648\u0631\u064a\u0644\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:400\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0628\u064a\u0627\u0646\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-key=\"ad63541d4f\" data-product-id=\"25575\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25575\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25575\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25575\" data-product_sku=\"9789775239938\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;1984&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;1984&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25575\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25575\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-24607 status-publish first instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"4\" data-id=\"24607\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-id=\"24607\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\">200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>11&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u062d\u0627\u0641\u0638 \u0628\u0646 \u0623\u062d\u0645\u062f \u062d\u0643\u0645\u0649\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:159\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0641\u0636\u064a\u0644\u0629\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-key=\"ad63541d4f\" data-product-id=\"24607\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24607\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24607\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24607\" data-product_sku=\"9772972298\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24607\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24607\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27450 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"27450\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-id=\"27450\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\">Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthors: Sulaiman Ismail &amp; Yuslina Mohamed\r\nNumber of Pages: 153\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-key=\"ad63541d4f\" data-product-id=\"27450\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27450\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27450\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27450\" data-product_sku=\"MashreqPub1\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27450\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27450\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-24896 status-publish instock product_cat-811 has-post-thumbnail purchasable product-type-simple\" data-loop=\"6\" data-id=\"24896\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" data-id=\"13596\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\">Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>60&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641: \u0645\u062e\u062a\u0627\u0631 \u0627\u0644\u0637\u0627\u0647\u0631 \u062d\u0633\u064a\u0646\r\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a: 195\r\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0643\u062a\u0627\u0628 \u0645\u0639 CD\r\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\r\n\u0627\u0644\u0646\u0627\u0634\u0631: \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0644\u0644\u062c\u0645\u064a\u0639\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" data-key=\"ad63541d4f\" data-product-id=\"13596\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24896\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24896\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24896\" data-product_sku=\"Child1160\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24896\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24896\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27451 status-publish last instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"27451\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Beyond Borders &#8211; Circular Economy And Marketing\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" data-id=\"27451\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\">Beyond Borders &#8211; Circular Economy And Marketing<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Muhammad Tahir\r\nNumber of Pages: 128\r\nCover Type: Hardcover\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" data-key=\"ad63541d4f\" data-product-id=\"27451\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27451\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27451\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27451\" data-product_sku=\"MashreqPub2\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Beyond Borders - Circular Economy And Marketing&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Beyond Borders - Circular Economy And Marketing&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27451\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27451\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27452 status-publish first instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"27452\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" data-id=\"27452\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\">Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>28&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Ali Ali Gobaili Saged\r\nNumber of Pages: 130\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" data-key=\"ad63541d4f\" data-product-id=\"27452\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27452\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27452\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27452\" data-product_sku=\"MashreqPub3\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27452\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27452\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27453 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"9\" data-id=\"27453\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Humanizing Science Education &#8211; STS as a Model\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" data-id=\"27453\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\">Humanizing Science Education &#8211; STS as a Model<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Muhammad Yusuf\r\nNumber of Pages: 146\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" data-key=\"ad63541d4f\" data-product-id=\"27453\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27453\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27453\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27453\" data-product_sku=\"MashreqPub4\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Humanizing Science Education - STS as a Model&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Humanizing Science Education - STS as a Model&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27453\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27453\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27454 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"10\" data-id=\"27454\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Influence of Media on People and Society\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" data-id=\"27454\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\">Influence of Media on People and Society<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Ahmed Abdel-Malik\r\nNumber of Pages: 123\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" data-key=\"ad63541d4f\" data-product-id=\"27454\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27454\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27454\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27454\" data-product_sku=\"MashreqPub5\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Influence of Media on People and Society&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Influence of Media on People and Society&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27454\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27454\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27455 status-publish last instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"11\" data-id=\"27455\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-1\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Islamic Studies Book 1\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-1\/\" data-id=\"27455\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-1\/\">Islamic Studies Book 1<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>50&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Imam Nurdin Muhammad Ali\r\nNumber of Pages: 137\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-1\/\" data-key=\"ad63541d4f\" data-product-id=\"27455\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27455\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27455\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27455\" data-product_sku=\"MashreqPub6\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Islamic Studies Book 1&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Islamic Studies Book 1&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27455\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-1\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27455\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27456 status-publish first instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"12\" data-id=\"27456\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-2\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Islamic Studies Book 2\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-2\/\" data-id=\"27456\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-2\/\">Islamic Studies Book 2<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>50&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Imam Nurdin Muhammad Ali\r\nNumber of Pages: 132\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Dar Al-Mashreq International Book House\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-2\/\" data-key=\"ad63541d4f\" data-product-id=\"27456\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27456\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27456\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27456\" data-product_sku=\"MashreqPub7\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Islamic Studies Book 2&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Islamic Studies Book 2&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27456\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-2\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27456\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"wd-nav-pagin-wrap text-center wd-style-shape wd-hide-md-sm wd-hide-sm\">\n\t\t\t<ul class=\"wd-nav-pagin\"><\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t[\/vc_column][\/vc_row][vc_row woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243; woodmart_disable_overflow=&#8221;0&#8243;][vc_column][vc_empty_space height=&#8221;85px&#8221; woodmart_hide_large=&#8221;0&#8243; woodmart_hide_medium=&#8221;0&#8243; woodmart_hide_small=&#8221;0&#8243; woodmart_hide_extra_small=&#8221;0&#8243;][\/vc_column][vc_column css=&#8221;.vc_custom_1541507763869{padding-top: 0px !important;}&#8221; woodmart_parallax=&#8221;0&#8243; parallax_scroll=&#8221;no&#8221; woodmart_sticky_column=&#8221;false&#8221;]\n\t\t<div id=\"wd-61f25419c07b1\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-61f25419c07b1 wd-title-color-primary wd-title-style-underlined text-center wd-off-anim wpb_animate_when_almost_visible wpb_fadeInDown fadeInDown wd-anim-name_fadeInDown  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >\u0643\u062a\u0628 \u0639\u0631\u0628\u064a\u0629<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t\t<div id=\"\" class=\"wd-products-element wd-wpb\">\n\t\t\t\n\t\t\n\t\t\t\t\t<div class=\"products wd-products  grid-columns-4 elements-grid wd-grid-g products-bordered-grid\" data-paged=\"1\" data-atts=\"{&quot;items_per_page&quot;:&quot;10&quot;,&quot;columns&quot;:&quot;4&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;highlighted_products&quot;:&quot;0&quot;,&quot;products_bordered_grid&quot;:&quot;1&quot;,&quot;img_size&quot;:&quot;174x174&quot;,&quot;force_not_ajax&quot;:&quot;no&quot;}\" data-source=\"shortcode\" data-columns=\"4\" data-grid-gallery=\"\" style=\"--wd-col-lg:4;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:30px;--wd-gap-sm:10px;\">\n\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-27601 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"27601\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-scaled-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-scaled-174x174.jpg 174w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-400x400.jpg 400w\" sizes=\"auto, (max-width: 174px) 100vw, 174px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-id=\"27601\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\">(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>85&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0633\u0645 \u0627\u0644\u0643\u062a\u0627\u0628: \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u0651\u064e\u062d\u0652\u0648\u061f\r\n\u0627\u0644\u0645\u0624\u0644\u0641: \u0623\u062d\u0645\u062f \u0625\u0633\u0643\u0646\u062f\u0631.\r\n\u0627\u0644\u0646\u0627\u0634\u0631: \u062f\u0627\u0631 \u0627\u0644\u0644\u0624\u0644\u0624\u0629 \u0644\u0644\u0646\u0634\u0631 \u0648\u0627\u0644\u062a\u0648\u0632\u064a\u0639 (\u0627\u0644\u0645\u0646\u0635\u0648\u0631\u0629 - \u0645\u0635\u0631).\r\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629: \u0627\u0644\u0637\u0628\u0639\u0629 \u0627\u0644\u062a\u0627\u0633\u0639\u0629 \u0639\u0634\u0631\u0629 (2024 \u0645 - 1445 \u0647\u0640).\r\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641: \u063a\u0644\u0627\u0641 \u0648\u0631\u0642\u064a \u0639\u0627\u062f\u064a (Paperback).\r\n\u0631\u0642\u0645 \u0627\u0644\u0625\u064a\u062f\u0627\u0639: 4153 \/ 2022 \u0645.\r\n\r\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a: 552\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-key=\"ad63541d4f\" data-product-id=\"27601\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27601\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27601\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27601\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27601\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27601\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-25672 status-publish instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"2\" data-id=\"25672\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-id=\"25672\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\">11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>15&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u0639\u0635\u0627\u0645 \u0645\u0646\u0635\u0648\u0631\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:172\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0634\u0631\u0648\u0642\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-key=\"ad63541d4f\" data-product-id=\"25672\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25672\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25672\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25672\" data-product_sku=\"MASHCODE142\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25672\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25672\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-25575 status-publish last instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"3\" data-id=\"25575\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"1984\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"1984\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-id=\"25575\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\">1984<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u062c\u0648\u0631\u062c \u0627\u0648\u0631\u064a\u0644\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:400\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0628\u064a\u0627\u0646\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-key=\"ad63541d4f\" data-product-id=\"25575\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25575\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25575\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25575\" data-product_sku=\"9789775239938\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;1984&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;1984&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25575\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25575\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-24607 status-publish first instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"4\" data-id=\"24607\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-id=\"24607\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\">200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>11&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u062d\u0627\u0641\u0638 \u0628\u0646 \u0623\u062d\u0645\u062f \u062d\u0643\u0645\u0649\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:159\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0641\u0636\u064a\u0644\u0629\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-key=\"ad63541d4f\" data-product-id=\"24607\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24607\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24607\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24607\" data-product_sku=\"9772972298\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24607\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24607\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-27450 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"27450\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-174x174.jpg 174w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-400x400.jpg 400w\" sizes=\"auto, (max-width: 174px) 100vw, 174px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-id=\"27450\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\">Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthors: Sulaiman Ismail &amp; Yuslina Mohamed\r\nNumber of Pages: 153\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-key=\"ad63541d4f\" data-product-id=\"27450\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27450\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27450\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27450\" data-product_sku=\"MashreqPub1\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27450\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27450\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-24896 status-publish instock product_cat-811 has-post-thumbnail purchasable product-type-simple\" data-loop=\"6\" data-id=\"24896\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" data-id=\"13596\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\">Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>60&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641: \u0645\u062e\u062a\u0627\u0631 \u0627\u0644\u0637\u0627\u0647\u0631 \u062d\u0633\u064a\u0646\r\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a: 195\r\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0643\u062a\u0627\u0628 \u0645\u0639 CD\r\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\r\n\u0627\u0644\u0646\u0627\u0634\u0631: \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0644\u0644\u062c\u0645\u064a\u0639\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" data-key=\"ad63541d4f\" data-product-id=\"13596\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24896\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24896\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24896\" data-product_sku=\"Child1160\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24896\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24896\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-27451 status-publish last instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"27451\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Beyond Borders &#8211; Circular Economy And Marketing\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-174x174.jpg 174w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-400x400.jpg 400w\" sizes=\"auto, (max-width: 174px) 100vw, 174px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" data-id=\"27451\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\">Beyond Borders &#8211; Circular Economy And Marketing<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Muhammad Tahir\r\nNumber of Pages: 128\r\nCover Type: Hardcover\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" data-key=\"ad63541d4f\" data-product-id=\"27451\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27451\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27451\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27451\" data-product_sku=\"MashreqPub2\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Beyond Borders - Circular Economy And Marketing&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Beyond Borders - Circular Economy And Marketing&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27451\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27451\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-27452 status-publish first instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"27452\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" data-id=\"27452\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\">Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>28&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Ali Ali Gobaili Saged\r\nNumber of Pages: 130\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" data-key=\"ad63541d4f\" data-product-id=\"27452\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27452\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27452\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27452\" data-product_sku=\"MashreqPub3\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27452\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27452\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-27453 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"9\" data-id=\"27453\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Humanizing Science Education &#8211; STS as a Model\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-174x174.jpg 174w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-400x400.jpg 400w\" sizes=\"auto, (max-width: 174px) 100vw, 174px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" data-id=\"27453\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\">Humanizing Science Education &#8211; STS as a Model<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Muhammad Yusuf\r\nNumber of Pages: 146\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" data-key=\"ad63541d4f\" data-product-id=\"27453\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27453\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27453\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27453\" data-product_sku=\"MashreqPub4\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Humanizing Science Education - STS as a Model&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Humanizing Science Education - STS as a Model&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27453\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27453\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-col product-grid-item product product-no-swatches type-product post-27454 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"10\" data-id=\"27454\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Influence of Media on People and Society\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-174x174.jpg 174w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-400x400.jpg 400w\" sizes=\"auto, (max-width: 174px) 100vw, 174px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" data-id=\"27454\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\">Influence of Media on People and Society<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Ahmed Abdel-Malik\r\nNumber of Pages: 123\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-bottom-actions\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" data-key=\"ad63541d4f\" data-product-id=\"27454\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27454\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27454\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27454\" data-product_sku=\"MashreqPub5\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Influence of Media on People and Society&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Influence of Media on People and Society&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27454\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27454\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1635912188785{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243; woodmart_disable_overflow=&#8221;0&#8243; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221;][vc_column css=&#8221;.vc_custom_1495003905736{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;]\n\t\t<div id=\"wd-5e5e01415dd42\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5e5e01415dd42 wd-title-color-default wd-title-style-default text-center wd-off-anim wpb_animate_when_almost_visible wpb_fadeInDown fadeInDown wd-anim-name_fadeInDown vc_custom_1583219038166 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xl\" >Best Collection<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t\t\n\t\t\t<div id=\"carousel-508\" class=\"wd-carousel-container  wd-wpb  wd-products-element wd-products products\">\n\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t<div class=\" wd-carousel wd-grid scroll-init\" data-speed=\"5000\" data-wrap=\"yes\" data-autoplay=\"yes\" data-scroll_per_page=\"yes\" data-center_mode=\"yes\" style=\"--wd-col-lg:6;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27601 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"27601\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-scaled-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-id=\"27601\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\">(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>85&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0633\u0645 \u0627\u0644\u0643\u062a\u0627\u0628: \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u0651\u064e\u062d\u0652\u0648\u061f\r\n\u0627\u0644\u0645\u0624\u0644\u0641: \u0623\u062d\u0645\u062f \u0625\u0633\u0643\u0646\u062f\u0631.\r\n\u0627\u0644\u0646\u0627\u0634\u0631: \u062f\u0627\u0631 \u0627\u0644\u0644\u0624\u0644\u0624\u0629 \u0644\u0644\u0646\u0634\u0631 \u0648\u0627\u0644\u062a\u0648\u0632\u064a\u0639 (\u0627\u0644\u0645\u0646\u0635\u0648\u0631\u0629 - \u0645\u0635\u0631).\r\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629: \u0627\u0644\u0637\u0628\u0639\u0629 \u0627\u0644\u062a\u0627\u0633\u0639\u0629 \u0639\u0634\u0631\u0629 (2024 \u0645 - 1445 \u0647\u0640).\r\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641: \u063a\u0644\u0627\u0641 \u0648\u0631\u0642\u064a \u0639\u0627\u062f\u064a (Paperback).\r\n\u0631\u0642\u0645 \u0627\u0644\u0625\u064a\u062f\u0627\u0639: 4153 \/ 2022 \u0645.\r\n\r\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a: 552\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-key=\"ad63541d4f\" data-product-id=\"27601\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27601\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27601\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27601\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27601\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27601\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-25672 status-publish instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"2\" data-id=\"25672\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-id=\"25672\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\">11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>15&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u0639\u0635\u0627\u0645 \u0645\u0646\u0635\u0648\u0631\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:172\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0634\u0631\u0648\u0642\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-key=\"ad63541d4f\" data-product-id=\"25672\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25672\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25672\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25672\" data-product_sku=\"MASHCODE142\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25672\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25672\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-25575 status-publish last instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"3\" data-id=\"25575\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"1984\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"1984\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-id=\"25575\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\">1984<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u062c\u0648\u0631\u062c \u0627\u0648\u0631\u064a\u0644\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:400\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0628\u064a\u0627\u0646\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-key=\"ad63541d4f\" data-product-id=\"25575\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25575\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25575\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25575\" data-product_sku=\"9789775239938\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;1984&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;1984&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25575\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25575\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-24607 status-publish first instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"4\" data-id=\"24607\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-id=\"24607\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\">200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>11&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u062d\u0627\u0641\u0638 \u0628\u0646 \u0623\u062d\u0645\u062f \u062d\u0643\u0645\u0649\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:159\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0641\u0636\u064a\u0644\u0629\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-key=\"ad63541d4f\" data-product-id=\"24607\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24607\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24607\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24607\" data-product_sku=\"9772972298\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24607\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24607\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27450 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"27450\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-id=\"27450\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\">Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthors: Sulaiman Ismail &amp; Yuslina Mohamed\r\nNumber of Pages: 153\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-key=\"ad63541d4f\" data-product-id=\"27450\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27450\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27450\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27450\" data-product_sku=\"MashreqPub1\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27450\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27450\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-24896 status-publish instock product_cat-811 has-post-thumbnail purchasable product-type-simple\" data-loop=\"6\" data-id=\"24896\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" data-id=\"13596\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\">Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>60&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641: \u0645\u062e\u062a\u0627\u0631 \u0627\u0644\u0637\u0627\u0647\u0631 \u062d\u0633\u064a\u0646\r\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a: 195\r\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0643\u062a\u0627\u0628 \u0645\u0639 CD\r\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\r\n\u0627\u0644\u0646\u0627\u0634\u0631: \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0644\u0644\u062c\u0645\u064a\u0639\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" data-key=\"ad63541d4f\" data-product-id=\"13596\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24896\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24896\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24896\" data-product_sku=\"Child1160\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24896\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24896\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27451 status-publish last instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"27451\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Beyond Borders &#8211; Circular Economy And Marketing\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" data-id=\"27451\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\">Beyond Borders &#8211; Circular Economy And Marketing<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Muhammad Tahir\r\nNumber of Pages: 128\r\nCover Type: Hardcover\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" data-key=\"ad63541d4f\" data-product-id=\"27451\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27451\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27451\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27451\" data-product_sku=\"MashreqPub2\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Beyond Borders - Circular Economy And Marketing&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Beyond Borders - Circular Economy And Marketing&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27451\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27451\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27452 status-publish first instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"27452\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" data-id=\"27452\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\">Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>28&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Ali Ali Gobaili Saged\r\nNumber of Pages: 130\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" data-key=\"ad63541d4f\" data-product-id=\"27452\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27452\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27452\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27452\" data-product_sku=\"MashreqPub3\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27452\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27452\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27453 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"9\" data-id=\"27453\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Humanizing Science Education &#8211; STS as a Model\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" data-id=\"27453\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\">Humanizing Science Education &#8211; STS as a Model<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Muhammad Yusuf\r\nNumber of Pages: 146\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" data-key=\"ad63541d4f\" data-product-id=\"27453\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27453\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27453\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27453\" data-product_sku=\"MashreqPub4\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Humanizing Science Education - STS as a Model&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Humanizing Science Education - STS as a Model&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27453\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27453\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27454 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"10\" data-id=\"27454\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Influence of Media on People and Society\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" data-id=\"27454\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\">Influence of Media on People and Society<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Ahmed Abdel-Malik\r\nNumber of Pages: 123\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" data-key=\"ad63541d4f\" data-product-id=\"27454\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27454\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27454\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27454\" data-product_sku=\"MashreqPub5\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Influence of Media on People and Society&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Influence of Media on People and Society&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27454\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27454\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27455 status-publish last instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"11\" data-id=\"27455\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-1\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Islamic Studies Book 1\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Isalmic-Studies-Book-1-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-1\/\" data-id=\"27455\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-1\/\">Islamic Studies Book 1<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>50&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Imam Nurdin Muhammad Ali\r\nNumber of Pages: 137\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-1\/\" data-key=\"ad63541d4f\" data-product-id=\"27455\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27455\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27455\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27455\" data-product_sku=\"MashreqPub6\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Islamic Studies Book 1&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Islamic Studies Book 1&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27455\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-1\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27455\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27456 status-publish first instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"12\" data-id=\"27456\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-2\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Islamic Studies Book 2\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-400x400.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-400x400.jpg 400w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Islmaic-Studies-Book-2-174x174.jpg 174w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-2\/\" data-id=\"27456\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-2\/\">Islamic Studies Book 2<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>50&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Imam Nurdin Muhammad Ali\r\nNumber of Pages: 132\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Dar Al-Mashreq International Book House\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-2\/\" data-key=\"ad63541d4f\" data-product-id=\"27456\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27456\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27456\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27456\" data-product_sku=\"MashreqPub7\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Islamic Studies Book 2&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Islamic Studies Book 2&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27456\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/islamic-studies-book-2\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27456\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t[\/vc_column][\/vc_row][vc_row woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243; woodmart_disable_overflow=&#8221;0&#8243;][vc_column][vc_empty_space height=&#8221;85px&#8221; woodmart_hide_large=&#8221;0&#8243; woodmart_hide_medium=&#8221;0&#8243; woodmart_hide_small=&#8221;0&#8243; woodmart_hide_extra_small=&#8221;0&#8243;][\/vc_column][vc_column css=&#8221;.vc_custom_1541507763869{padding-top: 0px !important;}&#8221; woodmart_parallax=&#8221;0&#8243; parallax_scroll=&#8221;no&#8221; woodmart_sticky_column=&#8221;false&#8221;]\n\t\t<div id=\"wd-61f2544c196cd\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-61f2544c196cd wd-title-color-primary wd-title-style-underlined text-center wd-off-anim wpb_animate_when_almost_visible wpb_fadeInDown fadeInDown wd-anim-name_fadeInDown  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >\u0645\u062c\u0645\u0648\u0639\u0647 \u0645\u0645\u064a\u0632\u0629<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t\t\n\t\t\t<div id=\"carousel-661\" class=\"wd-carousel-container  wd-wpb  wd-products-element wd-products products products-bordered-grid\">\n\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t<div class=\" wd-carousel wd-grid\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:4;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:30px;--wd-gap-sm:10px;\">\n\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27601 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"27601\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-scaled-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-scaled-174x174.jpg 174w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/07\/Image-12-400x400.jpg 400w\" sizes=\"auto, (max-width: 174px) 100vw, 174px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-id=\"27601\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\">(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>85&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0633\u0645 \u0627\u0644\u0643\u062a\u0627\u0628: \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u0651\u064e\u062d\u0652\u0648\u061f\r\n\u0627\u0644\u0645\u0624\u0644\u0641: \u0623\u062d\u0645\u062f \u0625\u0633\u0643\u0646\u062f\u0631.\r\n\u0627\u0644\u0646\u0627\u0634\u0631: \u062f\u0627\u0631 \u0627\u0644\u0644\u0624\u0644\u0624\u0629 \u0644\u0644\u0646\u0634\u0631 \u0648\u0627\u0644\u062a\u0648\u0632\u064a\u0639 (\u0627\u0644\u0645\u0646\u0635\u0648\u0631\u0629 - \u0645\u0635\u0631).\r\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629: \u0627\u0644\u0637\u0628\u0639\u0629 \u0627\u0644\u062a\u0627\u0633\u0639\u0629 \u0639\u0634\u0631\u0629 (2024 \u0645 - 1445 \u0647\u0640).\r\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641: \u063a\u0644\u0627\u0641 \u0648\u0631\u0642\u064a \u0639\u0627\u062f\u064a (Paperback).\r\n\u0631\u0642\u0645 \u0627\u0644\u0625\u064a\u062f\u0627\u0639: 4153 \/ 2022 \u0645.\r\n\r\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a: 552\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\" data-key=\"ad63541d4f\" data-product-id=\"27601\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27601\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27601\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27601\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;(\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0645\u0646 \u0627\u0644\u0642\u0631\u0627\u0646 \u0627\u0644\u0643\u0631\u064a\u0645 \u0648\u0627\u0644\u0633\u0646\u0629 \u0627\u0644\u0646\u0628\u0648\u064a\u0629) \u0643\u064a\u0641 \u062a\u062a\u0642\u0646 \u0627\u0644\u0646\u062d\u0648&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27601\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/%d8%a7%d9%84%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d9%85%d9%86-%d8%a7%d9%84%d9%82%d8%b1%d8%a7%d9%86-%d8%a7%d9%84%d9%83%d8%b1%d9%8a%d9%85-%d9%88%d8%a7%d9%84%d8%b3%d9%86%d8%a9-%d8%a7%d9%84%d9%86%d8%a8%d9%88\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27601\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-25672 status-publish instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"2\" data-id=\"25672\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/11\u0632\u0648\u062c\u0629-\u062a\u0641\u0634\u064a-\u0627\u0633\u0631\u0627\u0631-\u0627\u0644\u0627\u0632\u0648\u0627\u062c-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-id=\"25672\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\">11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>15&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u0639\u0635\u0627\u0645 \u0645\u0646\u0635\u0648\u0631\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:172\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0634\u0631\u0648\u0642\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\" data-key=\"ad63541d4f\" data-product-id=\"25672\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25672\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25672\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25672\" data-product_sku=\"MASHCODE142\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;11\u0632\u0648\u062c\u0629 \u062a\u0641\u0634\u064a \u0627\u0633\u0631\u0627\u0631 \u0627\u0644\u0627\u0632\u0648\u0627\u062c&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25672\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/11%d8%b2%d9%88%d8%ac%d8%a9-%d8%aa%d9%81%d8%b4%d9%8a-%d8%a7%d8%b3%d8%b1%d8%a7%d8%b1-%d8%a7%d9%84%d8%a7%d8%b2%d9%88%d8%a7%d8%ac\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25672\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-25575 status-publish last instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"3\" data-id=\"25575\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"1984\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/1984-1-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"1984\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-id=\"25575\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\">1984<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u062c\u0648\u0631\u062c \u0627\u0648\u0631\u064a\u0644\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:400\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0628\u064a\u0627\u0646\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\" data-key=\"ad63541d4f\" data-product-id=\"25575\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=25575\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_25575\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"25575\" data-product_sku=\"9789775239938\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;1984&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;1984&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_25575\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/1984\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"25575\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-24607 status-publish first instock has-post-thumbnail purchasable product-type-simple\" data-loop=\"4\" data-id=\"24607\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2022\/03\/200\u0633\u0624\u0627\u0644-\u0648\u062c\u0648\u0627\u0628-\u0641\u064a-\u0627\u0644\u0639\u0642\u064a\u062f\u0629-\u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-id=\"24607\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\">200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>11&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641:\u062d\u0627\u0641\u0638 \u0628\u0646 \u0623\u062d\u0645\u062f \u062d\u0643\u0645\u0649\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a:159\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0639\u0627\u062f\u064a\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\n\u0627\u0644\u0646\u0627\u0634\u0631:\u062f\u0627\u0631 \u0627\u0644\u0641\u0636\u064a\u0644\u0629\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\" data-key=\"ad63541d4f\" data-product-id=\"24607\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24607\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24607\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24607\" data-product_sku=\"9772972298\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;200\u0633\u0624\u0627\u0644 \u0648\u062c\u0648\u0627\u0628 \u0641\u064a \u0627\u0644\u0639\u0642\u064a\u062f\u0629 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u064a\u0629&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24607\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/200%d8%b3%d8%a4%d8%a7%d9%84-%d9%88%d8%ac%d9%88%d8%a7%d8%a8-%d9%81%d9%8a-%d8%a7%d9%84%d8%b9%d9%82%d9%8a%d8%af%d8%a9-%d8%a7%d9%84%d8%a5%d8%b3%d9%84%d8%a7%d9%85%d9%8a%d8%a9\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24607\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27450 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"27450\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-174x174.jpg 174w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Analisis-Keslipapan-Penggunaan-Frasa-Adjektif-Bahasa-Arab-400x400.jpg 400w\" sizes=\"auto, (max-width: 174px) 100vw, 174px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-id=\"27450\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\">Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthors: Sulaiman Ismail &amp; Yuslina Mohamed\r\nNumber of Pages: 153\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\" data-key=\"ad63541d4f\" data-product-id=\"27450\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27450\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27450\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27450\" data-product_sku=\"MashreqPub1\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Analisis Keslipapan Penggunaan Frasa Adjektif Bahasa Arab&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27450\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/analisis-keslipapan-penggunaan-frasa-adjektif-bahasa-arab\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27450\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-24896 status-publish instock product_cat-811 has-post-thumbnail purchasable product-type-simple\" data-loop=\"6\" data-id=\"24896\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/09\/Arabic-on-Air-\u0627\u0644\u0639\u0631\u0628\u064a\u0629-\u0639\u0644\u0649-\u0627\u0644\u0647\u0648\u0627\u0621-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" data-id=\"13596\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\">Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>60&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\t\u0627\u0644\u0645\u0624\u0644\u0641: \u0645\u062e\u062a\u0627\u0631 \u0627\u0644\u0637\u0627\u0647\u0631 \u062d\u0633\u064a\u0646\r\n\u0639\u062f\u062f \u0627\u0644\u0635\u0641\u062d\u0627\u062a: 195\r\n\u0646\u0648\u0639 \u0627\u0644\u063a\u0644\u0627\u0641:\u0643\u062a\u0627\u0628 \u0645\u0639 CD\r\n\u0631\u0642\u0645 \u0627\u0644\u0637\u0628\u0639\u0629:\u0627\u0644\u0623\u0648\u0644\u0649\r\n\u0627\u0644\u0646\u0627\u0634\u0631: \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0644\u0644\u062c\u0645\u064a\u0639\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\" data-key=\"ad63541d4f\" data-product-id=\"13596\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=24896\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24896\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"24896\" data-product_sku=\"Child1160\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Arabic on Air \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0647\u0648\u0627\u0621&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24896\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/product\/arabic-on-air-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9-%d8%b9%d9%84%d9%89-%d8%a7%d9%84%d9%87%d9%88%d8%a7%d8%a1\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"24896\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27451 status-publish last instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"27451\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Beyond Borders &#8211; Circular Economy And Marketing\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-174x174.jpg 174w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-1024x1024.jpg 1024w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Beyond-Borders-Circular-Economy-And-Marketing-400x400.jpg 400w\" sizes=\"auto, (max-width: 174px) 100vw, 174px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" data-id=\"27451\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\">Beyond Borders &#8211; Circular Economy And Marketing<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>40&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Muhammad Tahir\r\nNumber of Pages: 128\r\nCover Type: Hardcover\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\" data-key=\"ad63541d4f\" data-product-id=\"27451\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27451\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27451\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27451\" data-product_sku=\"MashreqPub2\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Beyond Borders - Circular Economy And Marketing&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Beyond Borders - Circular Economy And Marketing&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27451\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/beyond-borders-circular-economy-and-marketing\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27451\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27452 status-publish first instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"27452\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2021\/04\/Gangguan-Jin-dan-Rawatannya-Dari-Aspek-sains-perubatan-dan-Al-Quran-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" data-id=\"27452\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\">Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>28&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Ali Ali Gobaili Saged\r\nNumber of Pages: 130\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\" data-key=\"ad63541d4f\" data-product-id=\"27452\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27452\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27452\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27452\" data-product_sku=\"MashreqPub3\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Gangguan Jin dan Rawatannya Dari Aspek sains, perubatan dan Al Quran&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27452\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/gangguan-jin-dan-rawatannya-dari-aspek-sains-perubatan-dan-al-quran-2\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27452\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27453 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"9\" data-id=\"27453\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Humanizing Science Education &#8211; STS as a Model\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-174x174.jpg 174w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Humanizing-Science-Education-400x400.jpg 400w\" sizes=\"auto, (max-width: 174px) 100vw, 174px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" data-id=\"27453\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\">Humanizing Science Education &#8211; STS as a Model<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Muhammad Yusuf\r\nNumber of Pages: 146\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\" data-key=\"ad63541d4f\" data-product-id=\"27453\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27453\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27453\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27453\" data-product_sku=\"MashreqPub4\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Humanizing Science Education - STS as a Model&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Humanizing Science Education - STS as a Model&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27453\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/humanizing-science-education\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27453\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-base wd-hover-with-fade wd-fade-off product-grid-item product product-no-swatches type-product post-27454 status-publish instock product_cat-mashreq-publications has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"10\" data-id=\"27454\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"content-product-imagin\"><\/div>\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Influence of Media on People and Society\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"174\" src=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-174x174.jpg\" class=\"attachment-174x174 size-174x174\" alt=\"\" srcset=\"https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-174x174.jpg 174w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-300x300.jpg 300w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-150x150.jpg 150w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-768x768.jpg 768w, https:\/\/mashreq.com.my\/wp-content\/uploads\/2026\/05\/Influence-of-Media-on-People-and-Society-400x400.jpg 400w\" sizes=\"auto, (max-width: 174px) 100vw, 174px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wrapp-swatches\">\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" data-id=\"27454\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom product-information\">\n\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\">Influence of Media on People and Society<\/a><\/h3>\t\t\t\t<div class=\"product-rating-price\">\n\t\t\t<div class=\"wrapp-product-price\">\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>20&nbsp;<span class=\"woocommerce-Price-currencySymbol\"><\/span><\/bdi><\/span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"fade-in-block wd-scroll\">\n\t\t\t<div class=\"hover-content wd-more-desc\">\n\t\t\t\t<div class=\"hover-content-inner wd-more-desc-inner\">\n\t\t\t\t\tAuthor: Ahmed Abdel-Malik\r\nNumber of Pages: 123\r\nCover Type: Paperback\r\nEdition: First\r\nPublisher: Mashreq International for Books\t\t\t\t<\/div>\n\t\t\t\t<a href=\"#\" rel=\"nofollow\" class=\"wd-more-desc-btn\" aria-label=\"Read more description\"><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\" wd-buttons wd-pos-r-t\">\n\t\t\t\t<div class=\"wrap-wishlist-button\">\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\" data-key=\"ad63541d4f\" data-product-id=\"27454\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\">\n\t\t\t\t\t<a href=\"\/ar\/wp-json\/wp\/v2\/pages\/15091?add-to-cart=27454\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_27454\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"27454\" data-product_sku=\"MashreqPub5\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Influence of Media on People and Society&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Influence of Media on People and Society&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" role=\"button\"><span>\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_27454\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wrap-quickview-button\">\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/mashreq.com.my\/ar\/books\/influence-of-media-on-people-and-society\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"27454\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"wd-nav-pagin-wrap text-center wd-style-shape wd-hide-md-sm wd-hide-sm\">\n\t\t\t<ul class=\"wd-nav-pagin\"><\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1496413800534{margin-bottom: 4vh !important;}&#8221;][vc_column 0=&#8221;&#8221;][vc_images_carousel images=&#8221;3184,3182,3181,3180,3179&#8243; img_size=&#8221;full&#8221; onclick=&#8221;link_no&#8221; speed=&#8221;2000&#8243; slides_per_view=&#8221;5&#8243; autoplay=&#8221;yes&#8221; hide_pagination_control=&#8221;yes&#8221; wrap=&#8221;yes&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; css=&#8221;.vc_custom_1496220814548{margin-top: -40px !important;margin-bottom: 8vh !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1496220809434{padding-top: 0px !important;}&#8221;][rev_slider_vc alias=&#8221;main-slider-1&#8243;][\/vc_column][\/vc_row][vc_row woodmart_disable_overflow=&#8221;1&#8243; css=&#8221;.vc_custom_1496402498927{margin-bottom: 8vh !important;}&#8221; el_class=&#8221;bg-bottom&#8221;][vc_column 0=&#8221;&#8221; css=&#8221;.vc_custom_1496220821354{padding-top:<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-15091","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/mashreq.com.my\/ar\/wp-json\/wp\/v2\/pages\/15091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mashreq.com.my\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mashreq.com.my\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mashreq.com.my\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mashreq.com.my\/ar\/wp-json\/wp\/v2\/comments?post=15091"}],"version-history":[{"count":9,"href":"https:\/\/mashreq.com.my\/ar\/wp-json\/wp\/v2\/pages\/15091\/revisions"}],"predecessor-version":[{"id":15161,"href":"https:\/\/mashreq.com.my\/ar\/wp-json\/wp\/v2\/pages\/15091\/revisions\/15161"}],"wp:attachment":[{"href":"https:\/\/mashreq.com.my\/ar\/wp-json\/wp\/v2\/media?parent=15091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}